{"id":18247,"date":"2023-07-14T07:46:12","date_gmt":"2023-07-14T07:46:12","guid":{"rendered":"https:\/\/coinary.com\/?p=18247"},"modified":"2023-07-14T07:47:23","modified_gmt":"2023-07-14T07:47:23","slug":"regulacion-crypto-de-gary-gensler","status":"publish","type":"post","link":"https:\/\/coinary.com\/es\/blog\/regulacion-crypto-de-gary-gensler\/","title":{"rendered":"Gary Gensler: Pionero en el Rumbo de las Regulaciones Cripto en la SEC"},"content":{"rendered":"\n<p>Perm\u00edtanos revelar la historia de Gary Gensler, el Presidente de la SEC, cuyo camino est\u00e1 pavimentado con perseverancia y determinaci\u00f3n. Este nativo de Maryland no despert\u00f3 un d\u00eda siendo el l\u00edder de la SEC. Su trayectoria es un testimonio de un compromiso de toda la vida con el aprendizaje, la innovaci\u00f3n y el servicio.<\/p>\n\n\n\n<p>Al ponernos en los zapatos de Gary Gensler, nos damos cuenta de que su notable trayectoria comenz\u00f3 mucho antes de su nombramiento como Presidente de la SEC. Su excepcional historial en el servicio p\u00fablico, combinado con su pasi\u00f3n por la regulaci\u00f3n financiera, lo distingue. Pero es su incansable compromiso con la protecci\u00f3n de los inversores y la integridad del mercado lo que realmente lo coloca en una liga propia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Los A\u00f1os Formativos y Viaje Acad\u00e9mico de Gensler<\/strong><\/h2>\n\n\n\n<p>Nacido en una familia inmersa en una tradici\u00f3n de trabajo duro y determinaci\u00f3n, Gensler abraz\u00f3 la educaci\u00f3n como su piedra angular para el \u00e9xito. Sus aspiraciones intelectuales lo llevaron a la prestigiosa Escuela Wharton de la Universidad de Pensilvania, donde obtuvo una licenciatura en econom\u00eda. Aqu\u00ed, Gensler se form\u00f3 como un estudiante prodigioso y un prometedor economista.<\/p>\n\n\n\n<p>Lejos de descansar en sus laureles, Gensler agudiz\u00f3 a\u00fan m\u00e1s su perspicacia econ\u00f3mica al obtener un MBA en la estimada Escuela de Administraci\u00f3n Sloan del MIT. Los conocimientos y la experiencia adquiridos aqu\u00ed desempe\u00f1ar\u00edan un papel significativo en la configuraci\u00f3n de su enfoque hacia la regulaci\u00f3n financiera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gensler: El Innovador Financiero Pre-Criptomoneda<\/strong><\/h2>\n\n\n\n<p>Antes de que el mundo lo conociera como el ferviente cruzado de la regulaci\u00f3n de criptomonedas, Gensler era un veterano experimentado en el sector financiero tradicional. Un vistazo a su carrera temprana arroja luz sobre su r\u00e1pido ascenso en el mundo financiero. Comenz\u00f3 su viaje en <a href=\"https:\/\/www.goldmansachs.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Goldman Sachs<\/a>, uno de los bancos de inversi\u00f3n m\u00e1s reputados del mundo, donde perfeccion\u00f3 su destreza financiera.<\/p>\n\n\n\n<p>Un hito en su carrera fue el ascenso de Gensler al papel de socio en la divisi\u00f3n de renta fija y moneda del banco. Este per\u00edodo fue fundamental en la configuraci\u00f3n de la perspectiva de Gensler sobre los sistemas financieros y la gesti\u00f3n de riesgos. Su tiempo en Goldman Sachs estuvo marcado por sus incansables esfuerzos para asegurar que cada cliente, cada transacci\u00f3n, se manejaran con el m\u00e1s alto grado de integridad y profesionalismo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El Camino Pionero de Gensler en el Servicio P\u00fablico<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3-1024x682.jpg\" alt=\"foto de Garu gensler como Pionero  en el Servicio P\u00fablico\" class=\"wp-image-18260\" srcset=\"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3-1024x682.jpg 1024w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3-300x200.jpg 300w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3-768x511.jpg 768w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3-150x100.jpg 150w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La entrada de Gary Gensler en el \u00e1mbito del servicio p\u00fablico estuvo marcada por su compromiso para mejorar la regulaci\u00f3n financiera. Tras su exitosa carrera en Goldman Sachs, sirvi\u00f3 como Subsecretario del Tesoro para Finanzas Dom\u00e9sticas de 1999 a 2001 bajo la presidencia de Clinton, y luego como asesor del senador Paul Sarbanes en la elaboraci\u00f3n de la Ley Sarbanes-Oxley de 2002.<\/p>\n\n\n\n<p>Quiz\u00e1s uno de los per\u00edodos m\u00e1s notables en la carrera de servicio p\u00fablico de Gensler fue su mandato como Presidente de <a href=\"https:\/\/www.cftc.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\">la Comisi\u00f3n de Comercio de Futuros de Productos B\u00e1sicos (CFTC)<\/a>. Durante la administraci\u00f3n de Obama, lider\u00f3 cambios regulatorios significativos para mejorar la transparencia y responsabilidad en el mercado de derivados despu\u00e9s de la crisis financiera de 2008.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El Enfoque Revolucionario de Gensler a la Regulaci\u00f3n de las Criptomonedas<\/strong><\/h2>\n\n\n\n<p>En cuanto a las criptomonedas, el enfoque de Gensler est\u00e1 guiado por su profundo entendimiento del campo, habiendo dictado conferencias sobre tecnolog\u00eda blockchain y monedas digitales en el MIT. Su postura es clara: Aunque los activos digitales tienen promesa, tambi\u00e9n presentan riesgos, de ah\u00ed la necesidad de una regulaci\u00f3n cuidadosa.<\/p>\n\n\n\n<p>Como presidente de la SEC, Gensler ha enfatizado la importancia de proteger a los inversores en este mercado en r\u00e1pida evoluci\u00f3n. Ha abogado por una mayor supervisi\u00f3n de los intercambios de criptomonedas y ha pedido nuevas leyes para mantener el ritmo de los avances en este sector. Su papel como perro guardi\u00e1n regulatorio tiene como objetivo promover la confianza y la estabilidad en el floreciente mundo de las cripto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La Ascensi\u00f3n al Liderazgo de la SEC<\/strong><\/h2>\n\n\n\n<p>En 2021, el Presidente Joe Biden nombr\u00f3 a Gensler como Presidente de la <a href=\"https:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\">SEC<\/a>, reconociendo su vasta experiencia y un claro historial de robusta regulaci\u00f3n financiera. El nombramiento de Gensler se\u00f1al\u00f3 un nuevo cap\u00edtulo para la SEC con la promesa de aumentar la transparencia, fortificar la integridad del mercado y mejorar la protecci\u00f3n del inversor.<\/p>\n\n\n\n<p>El liderazgo de Gensler en la SEC tiene como objetivo salvaguardar los intereses de los inversores, mantener mercados justos y facilitar la formaci\u00f3n de capital. Su mandato como Presidente de la SEC se caracteriza por su b\u00fasqueda de una mayor divulgaci\u00f3n corporativa y su compromiso con la regulaci\u00f3n de los activos criptogr\u00e1ficos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Desempaquetando los Logros Notables de Gensler<\/strong><\/h2>\n\n\n\n<p>La carrera de Gensler est\u00e1 marcada por numerosos elogios y hitos. En el Departamento del Tesoro, fue instrumental en modernizar los sistemas financieros. Su liderazgo en la CFTC llev\u00f3 a reformas radicales en los mercados de derivados despu\u00e9s de la crisis financiera de 2008.<\/p>\n\n\n\n<p>Como Presidente de la SEC, Gensler ha priorizado la divulgaci\u00f3n de riesgos clim\u00e1ticos, ha examinado las regulaciones de SPAC y ha abogado por la supervisi\u00f3n de las criptomonedas. Estos logros destacan su firme compromiso para mejorar la integridad, resistencia y transparencia de los mercados financieros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Opiniones de Gensler sobre Bitcoin y Otras Criptomonedas<\/strong><\/h2>\n\n\n\n<p>Habiendo ense\u00f1ado <a href=\"https:\/\/coinary.com\/es\/learn\/que-es-blockchain\/\">tecnolog\u00eda blockchain<\/a> y criptomonedas en el MIT, Gensler conoce bien el potencial y las trampas de estos activos digitales. Reconoce <a href=\"https:\/\/coinary.com\/es\/learn\/que-es-bitcoin\/\">la innovaci\u00f3n de Bitcoin<\/a> y su papel como un almac\u00e9n especulativo de valor. Sin embargo, Gensler tambi\u00e9n es muy consciente de los riesgos que estas monedas digitales plantean para los inversores y el sistema financiero en general.<\/p>\n\n\n\n<p>Gensler cree en el potencial transformador de la tecnolog\u00eda, pero insiste en que debe operar dentro de un marco regulatorio para prevenir el fraude y la manipulaci\u00f3n. Su postura no es sobre sofocar la innovaci\u00f3n, sino sobre garantizar la protecci\u00f3n del inversor y la integridad del mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Moldeando el Futuro de la Regulaci\u00f3n de Criptomonedas: La Visi\u00f3n de Gensler<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"929\" height=\"523\" src=\"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-2.jpg\" alt=\"foto de perfil del comisionado de la SEc. La Visi\u00f3n de Gary Gensler en el mundo de las cripto\" class=\"wp-image-18257\" srcset=\"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-2.jpg 929w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-2-300x169.jpg 300w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-2-768x432.jpg 768w, https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Gary-Gensler-SEC-2-150x84.jpg 150w\" sizes=\"(max-width: 929px) 100vw, 929px\" \/><\/figure>\n\n\n\n<p>Como jefe de la SEC, el enfoque de Gensler hacia la futura regulaci\u00f3n de criptomonedas es de optimismo cauteloso. Ve la necesidad de un marco legal que no solo fomente la innovaci\u00f3n sino que tambi\u00e9n restrinja el riesgo de fraude e inestabilidad en el mercado de cripto.<\/p>\n\n\n\n<p>Gensler est\u00e1 impulsando una mayor claridad en las reglas de criptomonedas, centr\u00e1ndose en \u00e1reas como las ofertas iniciales de monedas (ICOs), <a href=\"https:\/\/coinary.com\/es\/learn\/que-es-defi-y-como-funcionan-las-finanzas-descentralizadas\/\">las finanzas descentralizadas (DeFi)<\/a>, y las plataformas de intercambios cripto. Sus planes futuros implican trabajar estrechamente con legisladores y otros reguladores para elaborar regulaciones que proporcionen claridad y protecci\u00f3n a los inversores sin sofocar el crecimiento de la industria de los activos digitales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un Cambio de Juego en la SEC<\/strong><\/h2>\n\n\n\n<p>La designaci\u00f3n de Gary Gensler como Presidente de la SEC marca un momento crucial para la regulaci\u00f3n financiera en los Estados Unidos. Su vasta experiencia, junto con su entendimiento complejo de los mercados financieros y las criptomonedas, lo convierten en una figura influyente en la formaci\u00f3n del futuro de las finanzas.<\/p>\n\n\n\n<p>La reputaci\u00f3n de Gensler como un regulador duro y su \u00e9nfasis en la protecci\u00f3n del inversor son evidentes en su enfoque hacia la regulaci\u00f3n de los activos cripto. Sin embargo, tambi\u00e9n reconoce el potencial que estas tecnolog\u00edas poseen. Este equilibrio entre acoger la innovaci\u00f3n y garantizar la estabilidad hace de Gensler un l\u00edder transformador en la SEC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Explora el viaje de Gary Gensler desde el MIT hasta la SEC, y c\u00f3mo est\u00e1 reformando el mundo cripto.<\/p>\n","protected":false},"author":5,"featured_media":18255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[85],"tags":[],"class_list":["post-18247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?<\/title>\n<meta name=\"description\" content=\"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coinary.com\/es\/blog\/gary-gensler-sec-chairman-profile\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?\" \/>\n<meta property=\"og:description\" content=\"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/\" \/>\n<meta property=\"og:site_name\" content=\"Coinary\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CoinaryLimited\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-14T07:46:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T07:47:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coinary\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@coinaryltd\" \/>\n<meta name=\"twitter:site\" content=\"@coinaryltd\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/blog\\\/regulacion-crypto-de-gary-gensler\\\/\"},\"author\":{\"name\":\"Coinary\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#\\\/schema\\\/person\\\/0c9f700c083ae41d98315b27f4e2fb90\"},\"headline\":\"Gary Gensler: Pionero en el Rumbo de las Regulaciones Cripto en la SEC\",\"datePublished\":\"2023-07-14T07:46:12+00:00\",\"dateModified\":\"2023-07-14T07:47:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/blog\\\/regulacion-crypto-de-gary-gensler\\\/\"},\"wordCount\":1298,\"publisher\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Ground-breaking-1.png\",\"articleSection\":[\"blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/blog\\\/regulacion-crypto-de-gary-gensler\\\/\",\"url\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/\",\"name\":\"\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Ground-breaking-1.png\",\"datePublished\":\"2023-07-14T07:46:12+00:00\",\"dateModified\":\"2023-07-14T07:47:23+00:00\",\"description\":\"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Ground-breaking-1.png\",\"contentUrl\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Ground-breaking-1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coinary.com\\\/blog\\\/gary-gensler-sec-chairman-profile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/coinary.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gary Gensler: Pionero en el Rumbo de las Regulaciones Cripto en la SEC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coinary.com\\\/es\\\/\",\"name\":\"Coinary\",\"description\":\"This is the official Website of Coinary LTD, the multinational entertainment company\",\"publisher\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coinary.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#organization\",\"name\":\"Coinary LTD\",\"url\":\"https:\\\/\\\/coinary.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/COINARY-LOGO_2.png\",\"contentUrl\":\"https:\\\/\\\/coinary.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/COINARY-LOGO_2.png\",\"width\":1080,\"height\":1080,\"caption\":\"Coinary LTD\"},\"image\":{\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CoinaryLimited\",\"https:\\\/\\\/x.com\\\/coinaryltd\",\"https:\\\/\\\/www.instagram.com\\\/coinaryltd\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coinary.com\\\/es\\\/#\\\/schema\\\/person\\\/0c9f700c083ae41d98315b27f4e2fb90\",\"name\":\"Coinary\",\"url\":\"https:\\\/\\\/coinary.com\\\/es\\\/author\\\/coinary\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?","description":"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coinary.com\/es\/blog\/gary-gensler-sec-chairman-profile\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?","og_description":"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.","og_url":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/","og_site_name":"Coinary","article_publisher":"https:\/\/www.facebook.com\/CoinaryLimited","article_published_time":"2023-07-14T07:46:12+00:00","article_modified_time":"2023-07-14T07:47:23+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png","type":"image\/png"}],"author":"Coinary","twitter_card":"summary_large_image","twitter_creator":"@coinaryltd","twitter_site":"@coinaryltd","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#article","isPartOf":{"@id":"https:\/\/coinary.com\/es\/blog\/regulacion-crypto-de-gary-gensler\/"},"author":{"name":"Coinary","@id":"https:\/\/coinary.com\/es\/#\/schema\/person\/0c9f700c083ae41d98315b27f4e2fb90"},"headline":"Gary Gensler: Pionero en el Rumbo de las Regulaciones Cripto en la SEC","datePublished":"2023-07-14T07:46:12+00:00","dateModified":"2023-07-14T07:47:23+00:00","mainEntityOfPage":{"@id":"https:\/\/coinary.com\/es\/blog\/regulacion-crypto-de-gary-gensler\/"},"wordCount":1298,"publisher":{"@id":"https:\/\/coinary.com\/es\/#organization"},"image":{"@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#primaryimage"},"thumbnailUrl":"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png","articleSection":["blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/coinary.com\/es\/blog\/regulacion-crypto-de-gary-gensler\/","url":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/","name":"\u00bfQui\u00e9n es Gary Gensler el Regulador Crypto de la SEC?","isPartOf":{"@id":"https:\/\/coinary.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#primaryimage"},"image":{"@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#primaryimage"},"thumbnailUrl":"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png","datePublished":"2023-07-14T07:46:12+00:00","dateModified":"2023-07-14T07:47:23+00:00","description":"Emb\u00e1rcate en un viaje informativo para entender c\u00f3mo Gary Gensler en la SEC est\u00e1 dictando las regulaciones cripto.","breadcrumb":{"@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#primaryimage","url":"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png","contentUrl":"https:\/\/coinary.com\/wp-content\/uploads\/2023\/07\/Ground-breaking-1.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/coinary.com\/blog\/gary-gensler-sec-chairman-profile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coinary.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Gary Gensler: Pionero en el Rumbo de las Regulaciones Cripto en la SEC"}]},{"@type":"WebSite","@id":"https:\/\/coinary.com\/es\/#website","url":"https:\/\/coinary.com\/es\/","name":"Coinary","description":"This is the official Website of Coinary LTD, the multinational entertainment company","publisher":{"@id":"https:\/\/coinary.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coinary.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/coinary.com\/es\/#organization","name":"Coinary LTD","url":"https:\/\/coinary.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/coinary.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/coinary.com\/wp-content\/uploads\/2022\/08\/COINARY-LOGO_2.png","contentUrl":"https:\/\/coinary.com\/wp-content\/uploads\/2022\/08\/COINARY-LOGO_2.png","width":1080,"height":1080,"caption":"Coinary LTD"},"image":{"@id":"https:\/\/coinary.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CoinaryLimited","https:\/\/x.com\/coinaryltd","https:\/\/www.instagram.com\/coinaryltd\/"]},{"@type":"Person","@id":"https:\/\/coinary.com\/es\/#\/schema\/person\/0c9f700c083ae41d98315b27f4e2fb90","name":"Coinary","url":"https:\/\/coinary.com\/es\/author\/coinary\/"}]}},"_links":{"self":[{"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/posts\/18247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/comments?post=18247"}],"version-history":[{"count":6,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/posts\/18247\/revisions"}],"predecessor-version":[{"id":18327,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/posts\/18247\/revisions\/18327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/media\/18255"}],"wp:attachment":[{"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/media?parent=18247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/categories?post=18247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coinary.com\/es\/wp-json\/wp\/v2\/tags?post=18247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}